{"id":110,"date":"2023-09-08T12:25:39","date_gmt":"2023-09-08T12:25:39","guid":{"rendered":"https:\/\/haege.sim-plexity.de\/?page_id=110"},"modified":"2024-03-25T08:12:30","modified_gmt":"2024-03-25T08:12:30","slug":"gender-hinweis","status":"publish","type":"page","link":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/","title":{"rendered":"Gender-Hinweis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"110\" class=\"elementor elementor-110\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e5d7cc elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2e5d7cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57ea75c\" data-id=\"57ea75c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d86a671 elementor-widget elementor-widget-heading\" data-id=\"d86a671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Gender-Hinweis<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77e1848 elementor-widget elementor-widget-text-editor\" data-id=\"77e1848\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Weil uns Gleichberechtigung, aber auch optimale Lesbarkeit wichtig sind!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e150cc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e150cc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53151f1\" data-id=\"53151f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f77da24 elementor-widget elementor-widget-spacer\" data-id=\"f77da24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-249ce4f elementor-widget elementor-widget-text-editor\" data-id=\"249ce4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Sinne einer besseren Lesbarkeit der Texte wurde die m\u00e4nnliche Form von personenbezogenen Hauptw\u00f6rtern gew\u00e4hlt. Dies impliziert keinesfalls eine Benachteiligung des weiblichen Geschlechts. Frauen und M\u00e4nner m\u00f6gen sich von den Inhalten unseres Handbuchs gleicherma\u00dfen angesprochen f\u00fchlen.<\/p>\n<p>Wir danken f\u00fcr Ihr Verst\u00e4ndnis.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a651bb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a651bb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa25d7d\" data-id=\"fa25d7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gender-Hinweis Weil uns Gleichberechtigung, aber auch optimale Lesbarkeit wichtig sind! Im Sinne einer besseren Lesbarkeit der Texte wurde die m\u00e4nnliche Form von personenbezogenen Hauptw\u00f6rtern gew\u00e4hlt. Dies impliziert keinesfalls eine Benachteiligung des weiblichen Geschlechts. Frauen und M\u00e4nner m\u00f6gen sich von den Inhalten unseres Handbuchs gleicherma\u00dfen angesprochen f\u00fchlen. Wir danken f\u00fcr Ihr Verst\u00e4ndnis.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":102,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-110","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gender-Hinweis - H\u00e4ge Bau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gender-Hinweis - H\u00e4ge Bau\" \/>\n<meta property=\"og:description\" content=\"Gender-Hinweis Weil uns Gleichberechtigung, aber auch optimale Lesbarkeit wichtig sind! Im Sinne einer besseren Lesbarkeit der Texte wurde die m\u00e4nnliche Form von personenbezogenen Hauptw\u00f6rtern gew\u00e4hlt. Dies impliziert keinesfalls eine Benachteiligung des weiblichen Geschlechts. Frauen und M\u00e4nner m\u00f6gen sich von den Inhalten unseres Handbuchs gleicherma\u00dfen angesprochen f\u00fchlen. Wir danken f\u00fcr Ihr Verst\u00e4ndnis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/\" \/>\n<meta property=\"og:site_name\" content=\"H\u00e4ge Bau\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T08:12:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/\",\"url\":\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/\",\"name\":\"Gender-Hinweis - H\u00e4ge Bau\",\"isPartOf\":{\"@id\":\"https:\/\/www.haege-baucenter.de\/#website\"},\"datePublished\":\"2023-09-08T12:25:39+00:00\",\"dateModified\":\"2024-03-25T08:12:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.haege-baucenter.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rechtliches\",\"item\":\"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gender-Hinweis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.haege-baucenter.de\/#website\",\"url\":\"https:\/\/www.haege-baucenter.de\/\",\"name\":\"H\u00e4ge Bau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.haege-baucenter.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gender-Hinweis - H\u00e4ge Bau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/","og_locale":"de_DE","og_type":"article","og_title":"Gender-Hinweis - H\u00e4ge Bau","og_description":"Gender-Hinweis Weil uns Gleichberechtigung, aber auch optimale Lesbarkeit wichtig sind! Im Sinne einer besseren Lesbarkeit der Texte wurde die m\u00e4nnliche Form von personenbezogenen Hauptw\u00f6rtern gew\u00e4hlt. Dies impliziert keinesfalls eine Benachteiligung des weiblichen Geschlechts. Frauen und M\u00e4nner m\u00f6gen sich von den Inhalten unseres Handbuchs gleicherma\u00dfen angesprochen f\u00fchlen. Wir danken f\u00fcr Ihr Verst\u00e4ndnis.","og_url":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/","og_site_name":"H\u00e4ge Bau","article_modified_time":"2024-03-25T08:12:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/","url":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/","name":"Gender-Hinweis - H\u00e4ge Bau","isPartOf":{"@id":"https:\/\/www.haege-baucenter.de\/#website"},"datePublished":"2023-09-08T12:25:39+00:00","dateModified":"2024-03-25T08:12:30+00:00","breadcrumb":{"@id":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/gender-hinweis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.haege-baucenter.de\/"},{"@type":"ListItem","position":2,"name":"Rechtliches","item":"https:\/\/www.haege-baucenter.de\/index.php\/rechtliches\/"},{"@type":"ListItem","position":3,"name":"Gender-Hinweis"}]},{"@type":"WebSite","@id":"https:\/\/www.haege-baucenter.de\/#website","url":"https:\/\/www.haege-baucenter.de\/","name":"H\u00e4ge Bau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haege-baucenter.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/pages\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":10,"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/pages\/110\/revisions"}],"predecessor-version":[{"id":1399,"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/pages\/110\/revisions\/1399"}],"up":[{"embeddable":true,"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/pages\/102"}],"wp:attachment":[{"href":"https:\/\/www.haege-baucenter.de\/index.php\/wp-json\/wp\/v2\/media?parent=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}